{"id":1129,"date":"2011-06-19T11:01:36","date_gmt":"2011-06-19T09:01:36","guid":{"rendered":"http:\/\/www.butterbemme.de\/blog\/?p=1129"},"modified":"2011-06-19T11:01:36","modified_gmt":"2011-06-19T09:01:36","slug":"titelwoche-achtung-sport","status":"publish","type":"post","link":"https:\/\/www.butterbemme.de\/blog\/2011\/06\/19\/titelwoche-achtung-sport\/","title":{"rendered":"Titelwoche &#8211; Achtung Sport ;-)"},"content":{"rendered":"<p>Was f\u00fcr eine Sport-Woche!<\/p>\n<ul>\n<li>Dirk Nowitzki mit den Dalles Mavericks wird NBA-Champion. Zum ersten mal seit Michael Jordan hab ich mir wieder ein Playoff-Final-Spiel live angeschaut. Was f\u00fcr eine Nacht<\/li>\n<li>mein Fu\u00dfball-Verein als aktiver Spieler steigt mit einen Wahnsinns Kraftakt auf.<\/li>\n<li>das Highlight f\u00fcr mich: die Boston Bruins gewinnen nach 39 Jahren wieder den Stanley Cup. Der Hammer! Damit konnten sich erstmals 2 Deutsche einen Major-Sports-Titel in den USA sichern.<\/li>\n<li>und dann gestern noch der glorreiche Abschluss, in dem Freak-City Bamberg den Gewinn der deutschen Basketball-Meisterschaft gegen Alba Berlin feiern konnte<\/li>\n<\/ul>\n<p>Aus sportlicher Sicht werd ich diese Woche wohl so schnell nicht vergessen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Was f\u00fcr eine Sport-Woche! Dirk Nowitzki mit den Dalles Mavericks wird NBA-Champion. Zum ersten mal seit Michael Jordan hab ich mir wieder ein Playoff-Final-Spiel live angeschaut. Was f\u00fcr eine Nacht mein Fu\u00dfball-Verein als aktiver Spieler steigt mit einen Wahnsinns Kraftakt auf. das Highlight f\u00fcr mich: die Boston Bruins gewinnen nach 39 Jahren wieder den Stanley &hellip; <a href=\"https:\/\/www.butterbemme.de\/blog\/2011\/06\/19\/titelwoche-achtung-sport\/\" class=\"more-link\"><span class=\"screen-reader-text\">Titelwoche &#8211; Achtung Sport ;-)<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[52,53],"tags":[],"class_list":["post-1129","post","type-post","status-publish","format-standard","hentry","category-personliches","category-sportliches"],"_links":{"self":[{"href":"https:\/\/www.butterbemme.de\/blog\/wp-json\/wp\/v2\/posts\/1129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.butterbemme.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.butterbemme.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.butterbemme.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.butterbemme.de\/blog\/wp-json\/wp\/v2\/comments?post=1129"}],"version-history":[{"count":1,"href":"https:\/\/www.butterbemme.de\/blog\/wp-json\/wp\/v2\/posts\/1129\/revisions"}],"predecessor-version":[{"id":1130,"href":"https:\/\/www.butterbemme.de\/blog\/wp-json\/wp\/v2\/posts\/1129\/revisions\/1130"}],"wp:attachment":[{"href":"https:\/\/www.butterbemme.de\/blog\/wp-json\/wp\/v2\/media?parent=1129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.butterbemme.de\/blog\/wp-json\/wp\/v2\/categories?post=1129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.butterbemme.de\/blog\/wp-json\/wp\/v2\/tags?post=1129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}